{"id":221703,"date":"2021-03-07T23:21:00","date_gmt":"2021-03-08T05:21:00","guid":{"rendered":"https:\/\/runahr.com\/?p=467"},"modified":"2026-02-26T12:03:27","modified_gmt":"2026-02-26T18:03:27","slug":"que-es-una-afore-y-para-que-sirve","status":"publish","type":"post","link":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/","title":{"rendered":"AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador?"},"content":{"rendered":"<p>\u00bfSab\u00edas que una parte de tu salario se destina a una cuenta de ahorro para tu retiro? Y que esta cuenta es administrada por una instituci\u00f3n llamada AFORE? Aunque este sistema es obligatorio para todos los trabajadores en M\u00e9xico, muchas personas desconocen c\u00f3mo funciona y qu\u00e9 beneficios pueden obtener. En este art\u00edculo, despejaremos tus dudas y te mostraremos c\u00f3mo aprovechar al m\u00e1ximo tus ahorros para el retiro.<\/p>\n<p><a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/que-es-consar\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-1092510\" src=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX190-300x119.webp\" alt=\"Ver ahora Tip: \u00bfQu\u00e9 es el CONSAR?\" width=\"928\" height=\"368\" srcset=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX190-300x119.webp 300w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX190-1024x405.webp 1024w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX190-768x304.webp 768w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX190-1536x607.webp 1536w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX190-2048x809.webp 2048w\" sizes=\"(max-width: 928px) 100vw, 928px\" \/><\/a><\/p>\n<h2><span>\u00bfQu\u00e9 son las AFORES?<\/span><\/h2>\n<p style=\"text-align: left;\"><span>Una <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/afore-que-es-y-para-que-sirve\/\">Administradora de Fondos para el Retiro (AFORE)<\/a> es la encargada de administrar los recursos pertenecientes al fondo para el <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/retiro\/\">retiro<\/a>, derivados de las aportaciones que realizan los patrones y trabajadores que est\u00e1n afiliados al <a href=\"https:\/\/runahr.com\/mx\/nomina\/que-es-el-imss\/\">Instituto Mexicano del Seguro Social (IMSS)<\/a><\/span><span>\u00a0o al <a href=\"https:\/\/runahr.com\/mx\/recursos\/seguros\/issste\/\">Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE)<\/a><\/span><span>.<\/span><\/p>\n<h2><span>\u00bfPara qu\u00e9 sirven las AFORES?<\/span><\/h2>\n<p><span>La funcionalidad principal de las AFORES es administrar, invertir y generar el mayor <a href=\"https:\/\/runahr.com\/mx\/recursos\/hr-management\/rendimiento\/\">rendimiento<\/a> posible de las aportaciones que realizan los trabajadores. Sin embargo, los ahorros acumulados var\u00edan dependiendo de los siguientes factores:\u00a0<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span><a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/salario\/\">Salario<\/a> percibido\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>El porcentaje de comisi\u00f3n que cobra la AFORE<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>El rendimiento que generan los ahorros\u00a0<\/span><\/li>\n<\/ol>\n<p><span>Adem\u00e1s, de acuerdo con la <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-la-consar-y-cuales-son-sus-funciones\/\">Comisi\u00f3n Nacional del Sistema de Ahorro (CONSAR)<\/a><\/span><span>\u00a0contar con una AFORE que administre los ahorros de manera individual tiene los siguientes <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/beneficios\/\">beneficios<\/a>:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Administraci\u00f3n e inversi\u00f3n adecuada de los recursos\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Generaci\u00f3n de mayores rendimientos\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Obtenci\u00f3n de un <a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/estado-de-cuenta\/\">estado de cuenta<\/a> para llevar un control de ahorros eficiente\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Servicio v\u00eda telef\u00f3nica o presencial para dudas o aclaraciones<\/span><\/li>\n<\/ul>\n<h2><span>\u00bfC\u00f3mo funcionan las AFORES?<\/span><\/h2>\n<p><span>La ley del <a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/que-es-el-sar-2\/\">Sistema de Ahorro para el Retiro (SAR)<\/a><\/span><span>\u00a0especifica que cada empleado tiene derecho a una cuenta individual proveniente de una instituci\u00f3n financiera dedicada a la administraci\u00f3n de sus fondos para el retiro. Por lo cual, una AFORE es la encargada de concentrar en una cuenta todas las cuotas que se realizan mediante el descuento al salario del <a href=\"https:\/\/runahr.com\/mx\/recursos\/hr-management\/trabajador\/\">trabajador<\/a> junto a las contribuciones que realiza el patr\u00f3n y el gobierno.\u00a0<\/span><\/p>\n<p><span>Se pueden hacer aportaciones voluntarias generando un ahorro opcional extra o adicional a la cuenta individual de AFORE y as\u00ed usar estos recursos para aumentar el monto de la <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/pension\/\">pensi\u00f3n<\/a>.<\/span><\/p>\n<p><span>El dinero concentrado en la cuenta individual se invierte a trav\u00e9s de una <a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/siefore\/\">Sociedad de Inversi\u00f3n Especializada en Fondos para el Retiro (SIEFORE)<\/a><\/span><span>\u00a0para que a la larga se tengan mayores rendimientos y as\u00ed los ahorros crezcan de forma que garanticen un patrimonio estable para el trabajador al momento de su retiro.\u00a0<\/span><\/p>\n<p><span>Las inversiones realizadas son reguladas por la CONSAR, para garantizar que los fondos sean invertidos, generen retornos y no haya p\u00e9rdidas que afecten los recursos y patrimonio del trabajador.\u00a0<\/span><\/p>\n<p><span>Estos esquemas de inversi\u00f3n var\u00edan seg\u00fan la edad del empleado. Esto quiere decir que mientras m\u00e1s joven sea, su AFORE se invierte en activos de mayor riesgo que pueden generar un porcentaje mayor de rendimientos. Mientras que, a mayor edad, el riesgo en las inversiones es menor pero los rendimientos y ahorro no corren riesgo. La CONSAR es la encargada de regular todo lo anterior.<\/span><\/p>\n<h2><span>\u00bfQu\u00e9 relaci\u00f3n tiene la AFORE con la n\u00f3mina?<\/span><\/h2>\n<p><span>Todas las personas asalariadas tienen una cuenta individual y \u00fanica, en donde se acumulan sus recursos. \u00c9stos ser\u00e1n descontados de manera autom\u00e1tica v\u00eda <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-nomina\/\">n\u00f3mina<\/a>, bajo el concepto de IMSS y as\u00ed el patr\u00f3n podr\u00e1 deducir las cantidades que el trabajador est\u00e1 obligado a pagar para su<\/span> <span>cesant\u00eda y vejez<\/span><span>.<\/span><\/p>\n<p><span>Como empresa se debe registrar a trav\u00e9s del c\u00e1lculo de las provisiones generadas en la n\u00f3mina en los apartados de retiro, cesant\u00eda y vejez que posteriormente son pagados en la l\u00ednea de captura del <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/sipare\/\">Sistema de Pago Referenciado (SIPARE)<\/a><\/span><span>\u00a0que es el instituto que da a conocer las cantidades destinadas al AFORE.<\/span><\/p>\n<p><a href=\"https:\/\/recursos.runahr.com\/guia-practica-imss-para-emprendedores\"><img decoding=\"async\" class=\"alignnone  wp-image-1091550\" src=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX066-300x119.webp\" alt=\"Descargar Manual IMSS para empresas\" width=\"930\" height=\"369\" srcset=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX066-300x119.webp 300w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX066-1024x405.webp 1024w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX066-768x304.webp 768w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX066-1536x607.webp 1536w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/><\/a><\/p>\n<h2><span>\u00bfCu\u00e1les son los beneficios de contar con una AFORE?<\/span><\/h2>\n<p><span>Estar afiliado a una AFORE tiene beneficios como los siguientes:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Posees tu propia cuenta, \u00fanica e individual, en la que tu patr\u00f3n y t\u00fa podr\u00e1n realizar las aportaciones.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Tienes el derecho de recibir un informe detallado cuatrimestral que refleja lo que tienes ahorrado, el historial y los movimientos de tu cuenta.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>En caso de situaciones especiales, como <a href=\"https:\/\/runahr.com\/mx\/recursos\/hr-management\/desempleo\/\">desempleo<\/a> o matrimonio, podr\u00e1s disponer parcialmente de una cantidad de tus ahorros.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Si realizas cuotas voluntarias, tu ahorro puede incrementar. Esto te garantizar\u00e1 una mejor <a href=\"https:\/\/runahr.com\/mx\/recursos\/hr-management\/calidad-de-vida\/\">calidad de vida<\/a> y seguridad financiera al momento de tu retiro.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span>Si te quedas sin empleo, tu ahorro permanecer\u00e1 intacto y seguro en tu cuenta y por supuesto, sigue generando rendimientos.\u00a0<\/span><\/li>\n<\/ul>\n<h2><span>\u00bfC\u00f3mo realizar tu registro en una AFORE?<\/span><\/h2>\n<p><span>\u00a0Recuerda que para aplicar al AFORE es necesario contar con un empleo formal afiliado al IMSS o al ISSSTE, posteriormente:<\/span><\/p>\n<ol>\n<li><span>Contacta a la AFORE de tu preferencia y solicita la visita de uno de sus agentes promotores o acude a cualquiera de sus sucursales. <\/span>Tambi\u00e9n puedes realizar una pre-solicitud de registro a trav\u00e9s del portal <a href=\"http:\/\/www.e-sar.com.mx\/\">www.e-sar.com.mx<\/a>. Cuando hayas completado la pre-solicitud, la AFORE deber\u00e1 contactarte en un plazo no mayor a 6 d\u00edas h\u00e1biles para iniciar las gestiones.<\/li>\n<li>\u00a0Para tramitar tu registro, la AFORE conformar\u00e1 tu expediente de identificaci\u00f3n electr\u00f3nico, para lo cual te solicitar\u00e1 lo siguiente:\n<ul>\n<li><span>Datos Personales (como <\/span><a href=\"https:\/\/runahr.com\/mx\/nomina\/curp\/\"><span>Clave \u00danica de Registro de Poblaci\u00f3n (CURP)<\/span><\/a><span>, <\/span><a href=\"https:\/\/runahr.com\/mx\/aspectos-legales\/rfc\/\"><span>Registro Federal de Contribuyentes (RFC)<\/span><\/a><span> y<\/span><a href=\"https:\/\/runahr.com\/mx\/recursos\/hr-management\/nss\/\"> <span>N\u00famero de Seguridad Social (NSS)<\/span><\/a><span> del IMSS).<\/span><\/li>\n<li><span>Identificaci\u00f3n oficial<\/span><\/li>\n<li><a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/comprobante-de-domicilio\/\"><span>Comprobante de domicilio<\/span><\/a><\/li>\n<li><span>Una fotograf\u00eda digital de tu rostro, que ser\u00e1 tomada por el agente promotor<\/span><\/li>\n<li><span>Tu firma biom\u00e9trica (huellas digitales)<\/span><\/li>\n<li><span>Tu firma manuscrita digital<\/span><\/li>\n<\/ul>\n<\/li>\n<li><span>A trav\u00e9s de un medio electr\u00f3nico, la AFORE te dar\u00e1 la solicitud de registro (que contiene el contrato de administraci\u00f3n de fondos para el retiro) y el documento de rendimiento neto, en los que debes asentar tu nombre completo, firma biom\u00e9trica (huellas digitales) y firma manuscrita digital. Asimismo, la AFORE debe tomar un video en el que des tu consentimiento para el registro y confirmes tus datos personales.<\/span><\/li>\n<li>La AFORE te informar\u00e1 sobre el resultado de la solicitud de registro:\n<ul>\n<li><span>Si la solicitud es aceptada, deber\u00e1s enviar una constancia de registro al domicilio o al correo electr\u00f3nico que hayas proporcionado, dentro de los cinco d\u00edas h\u00e1biles siguientes a la fecha de conclusi\u00f3n del tr\u00e1mite.<\/span><\/li>\n<li><span>Si la solicitud es rechazada, dentro de los cinco d\u00edas h\u00e1biles siguientes a la fecha en que se dio ese resultado, deber\u00e1 enviar a tu domicilio o correo electr\u00f3nico un documento en el que se te informe del rechazo y los motivos que dieron lugar al mismo.<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<h2><span>\u00bfC\u00f3mo se cre\u00f3 la AFORE?<\/span><\/h2>\n<p><span>La AFORE ha cambiado mucho a lo largo de la historia. De 1943 a 1973 se implement\u00f3 el Sistema de Reparto, el cual consist\u00eda en que las aportaciones de los empleados activos se repart\u00edan en el pago de pensiones de quienes ya estaban retirados en aquel momento.<\/span><\/p>\n<p><span>Pero este m\u00e9todo empez\u00f3 a fallar porque dej\u00f3 de haber suficientes asalariados aportando recursos para pagar las pensiones de cada vez m\u00e1s jubilados. Antes entre 20 trabajadores pagaban la pensi\u00f3n de un jubilado, posteriormente una pensi\u00f3n era pagada solamente por cuatro.\u00a0<\/span><\/p>\n<p><span>Por este motivo, en 1997 despu\u00e9s de la expedici\u00f3n del SAR, nacen las AFORES y es aqu\u00ed donde se define que cada trabajador har\u00e1 aportaciones para su propio retiro.<\/span><\/p>\n<p><a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/que-es-jubilacion\/\"><img decoding=\"async\" class=\"alignnone  wp-image-1092678\" src=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX211-300x119.webp\" alt=\"Ver ahora Tip: \u00bfQu\u00e9 es la jubilaci\u00f3n?\" width=\"930\" height=\"369\" srcset=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX211-300x119.webp 300w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX211-1024x405.webp 1024w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX211-768x304.webp 768w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX211-1536x607.webp 1536w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSab\u00edas que una parte de tu salario se destina a una cuenta de ahorro para tu retiro? Y que esta cuenta es administrada por una instituci\u00f3n llamada AFORE? Aunque este sistema es obligatorio para todos los trabajadores en M\u00e9xico, muchas personas desconocen c\u00f3mo funciona y qu\u00e9 beneficios pueden obtener. En este art\u00edculo, despejaremos tus dudas [&hellip;]<\/p>\n","protected":false},"author":87,"featured_media":1045933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_wp_applaud_exclude":false,"footnotes":""},"categories":[170,190],"tags":[1098,1297,369],"class_list":["post-221703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nomina","category-recursos","tag-afore","tag-articulo","tag-nomina-mx"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador? | MX | Runa HR<\/title>\n<meta name=\"description\" content=\"Las AFORES se encargan de administrar aportaciones que realizan los patrones y trabajadores afiliados al IMSS o al ISSSTE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador? | MX | Runa HR\" \/>\n<meta property=\"og:description\" content=\"Las AFORES se encargan de administrar aportaciones que realizan los patrones y trabajadores afiliados al IMSS o al ISSSTE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/\" \/>\n<meta property=\"og:site_name\" content=\"Runa HR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/runahr\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-08T05:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T18:03:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/AFORE-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1071\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Runa HR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@runahr\" \/>\n<meta name=\"twitter:site\" content=\"@runahr\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"it-tools\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador? | MX | Runa HR","description":"Las AFORES se encargan de administrar aportaciones que realizan los patrones y trabajadores afiliados al IMSS o al ISSSTE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/","og_locale":"es_MX","og_type":"article","og_title":"AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador? | MX | Runa HR","og_description":"Las AFORES se encargan de administrar aportaciones que realizan los patrones y trabajadores afiliados al IMSS o al ISSSTE.","og_url":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/","og_site_name":"Runa HR","article_publisher":"https:\/\/www.facebook.com\/runahr\/","article_published_time":"2021-03-08T05:21:00+00:00","article_modified_time":"2026-02-26T18:03:27+00:00","og_image":[{"width":2560,"height":1071,"url":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/AFORE-scaled.png","type":"image\/png"}],"author":"Runa HR","twitter_card":"summary_large_image","twitter_creator":"@runahr","twitter_site":"@runahr","twitter_misc":{"Escrito por":"it-tools","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/#article","isPartOf":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/"},"author":{"name":"it-tools","@id":"https:\/\/runahr.com\/mx\/#\/schema\/person\/5a22fa36c8ff828a0720d10281e38009"},"headline":"AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador?","datePublished":"2021-03-08T05:21:00+00:00","dateModified":"2026-02-26T18:03:27+00:00","mainEntityOfPage":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/"},"wordCount":1247,"publisher":{"@id":"https:\/\/runahr.com\/mx\/#organization"},"image":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/#primaryimage"},"thumbnailUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/AFORE-scaled.png","keywords":["AFORE","Art\u00edculo","N\u00f3mina"],"articleSection":["N\u00f3mina","Recursos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/","url":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/","name":"AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador? | MX | Runa HR","isPartOf":{"@id":"https:\/\/runahr.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/#primaryimage"},"image":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/#primaryimage"},"thumbnailUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/AFORE-scaled.png","datePublished":"2021-03-08T05:21:00+00:00","dateModified":"2026-02-26T18:03:27+00:00","description":"Las AFORES se encargan de administrar aportaciones que realizan los patrones y trabajadores afiliados al IMSS o al ISSSTE.","breadcrumb":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/#primaryimage","url":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/AFORE-scaled.png","contentUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/AFORE-scaled.png","width":2560,"height":1071,"caption":"AFORE"},{"@type":"BreadcrumbList","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-una-afore-y-para-que-sirve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/runahr.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Recursos","item":"https:\/\/runahr.com\/mx\/category\/recursos\/"},{"@type":"ListItem","position":3,"name":"N\u00f3mina","item":"https:\/\/runahr.com\/mx\/category\/recursos\/nomina\/"},{"@type":"ListItem","position":4,"name":"AFORES: \u00bfQu\u00e9 son? \u00bfPara qu\u00e9 sirven al trabajador?"}]},{"@type":"WebSite","@id":"https:\/\/runahr.com\/mx\/#website","url":"https:\/\/runahr.com\/mx\/","name":"Runa HR","description":"Software de N\u00f3mina y Gesti\u00f3n de RRHH","publisher":{"@id":"https:\/\/runahr.com\/mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/runahr.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/runahr.com\/mx\/#organization","name":"Runa HR","url":"https:\/\/runahr.com\/mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/runahr.com\/mx\/#\/schema\/logo\/image\/","url":"https:\/\/runahr.com\/wp-content\/uploads\/2018\/05\/xDzHFcQY_400x400.jpg","contentUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2018\/05\/xDzHFcQY_400x400.jpg","width":400,"height":400,"caption":"Runa HR"},"image":{"@id":"https:\/\/runahr.com\/mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/runahr\/","https:\/\/x.com\/runahr","https:\/\/www.instagram.com\/runahr\/","https:\/\/mx.linkedin.com\/company\/runahr","https:\/\/www.youtube.com\/channel\/UCAZ21FupFMLIb1c7PPaU6Ew"]},{"@type":"Person","@id":"https:\/\/runahr.com\/mx\/#\/schema\/person\/5a22fa36c8ff828a0720d10281e38009","name":"it-tools","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68a146e44420ce6688dd5b32f006e4fc28c82828950327acf34ceb7288a433f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68a146e44420ce6688dd5b32f006e4fc28c82828950327acf34ceb7288a433f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68a146e44420ce6688dd5b32f006e4fc28c82828950327acf34ceb7288a433f0?s=96&d=mm&r=g","caption":"it-tools"},"url":"https:\/\/runahr.com\/mx\/author\/it-tools\/"}]}},"_links":{"self":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/posts\/221703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/comments?post=221703"}],"version-history":[{"count":0,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/posts\/221703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/media\/1045933"}],"wp:attachment":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/media?parent=221703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/categories?post=221703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/tags?post=221703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}