{"id":701,"date":"2017-11-09T00:21:32","date_gmt":"2017-11-09T06:21:32","guid":{"rendered":"https:\/\/runahr.com\/?p=701"},"modified":"2026-02-21T14:26:14","modified_gmt":"2026-02-21T20:26:14","slug":"como-seleccionar-el-pac-adecuado","status":"publish","type":"post","link":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/","title":{"rendered":"\u00bfC\u00f3mo seleccionar un PAC adecuado?"},"content":{"rendered":"<p style=\"text-align: left;\">Fue en 2014 cuando el <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/sat\/\">Servicio de Administraci\u00f3n Tributaria (SAT)<\/a> comand\u00f3 obligatoria la expedici\u00f3n de facturas electr\u00f3nicas para los contribuyentes f\u00edsicos y morales con actividad empresarial. Desde entonces, para desempe\u00f1ar sus actividades dentro de las normas es necesario que los contribuyentes cuenten con este servicio. Para lo cual es necesario un <a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/pac\/\">Proveedor Autorizado de Certificaci\u00f3n (PAC)<\/a>.<\/p>\n<p><a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/que-es-un-pac\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-1092822\" src=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX226-300x119.webp\" alt=\"Ver ahora Tip: \u00bfQu\u00e9 es un PAC?\" width=\"1351\" height=\"536\" srcset=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX226-300x119.webp 300w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX226-1024x405.webp 1024w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX226-768x304.webp 768w\" sizes=\"(max-width: 1351px) 100vw, 1351px\" \/><\/a><\/p>\n<h2>\u00bfQu\u00e9 es un Proveedor Autorizado de Certificaci\u00f3n (PAC)?<\/h2>\n<p style=\"text-align: left;\">El PAC es el encargado de realizar la certificaci\u00f3n y presentar ante el SAT estas facturas electr\u00f3nicas. \u00bfD\u00f3nde puedo encontrar un PAC? Sin duda nos podemos topar con muchos que dicen ser proveedores y ofertan un servicio.<\/p>\n<p style=\"text-align: left;\">Sin embargo, aparece publicado en la p\u00e1gina del SAT un listado con s\u00f3lo 79 proveedores certificados y avalados para cumplir con esta funci\u00f3n. Los servicios que realizan estos PAC van desde validar los requisitos del comprobante hasta asignarle un <a href=\"https:\/\/runahr.com\/mx\/recursos\/aspectos-legales\/folio-fiscal\/#:~:text=El%20folio%20fiscal%2C%20mejor%20conocido,una%20factura%20electr%C3%B3nica%20correctamente%20elaborada.\">folio fiscal<\/a> e incorporar el <a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/certificado-de-sello-digital-que-es-y-para-que-sirve\/\">certificado de sello digital<\/a> del SAT a cada factura.<\/p>\n<p><a href=\"https:\/\/recursos.runahr.com\/guia-de-cfdi-4-0\"><img decoding=\"async\" class=\"alignnone  wp-image-1091246\" src=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX027-300x118.webp\" alt=\"Descargar gu\u00eda de CFDI 4.0 mejores pr\u00e1cticas\" width=\"1355\" height=\"533\" srcset=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX027-300x118.webp 300w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX027-1024x403.webp 1024w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX027-768x302.webp 768w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX027-1536x604.webp 1536w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX027-2048x806.webp 2048w\" sizes=\"(max-width: 1355px) 100vw, 1355px\" \/><\/a><\/p>\n<h2 style=\"text-align: left;\">\u00bfC\u00f3mo s\u00e9 que el PAC que utilizo es apropiado, qu\u00e9 puntos debo considerar antes de elegir uno?<\/h2>\n<ul>\n<li style=\"text-align: left;\">Debe ser un proveedor autorizado. Recuerda que aquellos avalados por el SAT est\u00e1n publicados en la p\u00e1gina oficial.<\/li>\n<li style=\"text-align: left;\">Debe contar con un logotipo oficial. Para mayor seguridad, identifica si este corresponde con el nombre de la empresa y su <a href=\"https:\/\/runahr.com\/mx\/recursos\/comienza-tu-empresa\/que-es-la-razon-social-como-tramitarla-2\/\">raz\u00f3n social<\/a>.<\/li>\n<li style=\"text-align: left;\">Es aconsejable firmar un contrato por los servicios prestados. As\u00ed, si llega a ocurrir una anomal\u00eda o problema se puede notificar al SAT sobre el incumplimiento del proveedor.<\/li>\n<\/ul>\n<p style=\"text-align: left;\">Finalmente, es necesario aclarar que cada contribuyente tiene necesidades muy diferentes, por lo que estas son adem\u00e1s algunas consideraciones a tomar en cuenta para contratar un PAC seg\u00fan nuestro nivel de actividad:<\/p>\n<p style=\"text-align: left;\">Si se es un contribuyente que expide muy pocas facturas, en lugar de contratar a un proveedor externo, tiene la posibilidad de utilizar la facturaci\u00f3n gratuita disponible en la p\u00e1gina del SAT, pues ellos tienen como obligaci\u00f3n proveer todos las herramientas para que el contribuyente pueda cumplir con sus deberes fiscales.<\/p>\n<p style=\"text-align: left;\">Si se es un contribuyente que necesita de servicios especiales, considerar no s\u00f3lo que el PAC cuente con los requerimientos b\u00e1sicos. Sino buscar adem\u00e1s, de los proveedores acreditados, aqu\u00e9l que ofrezca tarifas que se adapten a su negocio, ya que los PAC suelen ser contratados por tarifas mensuales. Es recomendable probar las versiones gratuitas de los diferentes PAC verificados antes de contratar uno.<\/p>\n<p><a href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-deducir-y-timbrar-una-nomina-correctamente\/\"><img decoding=\"async\" class=\"alignnone  wp-image-1093054\" src=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX255-300x119.webp\" alt=\"Ver ahora Webinar: \u00bfC\u00f3mo deducir y timbrar una n\u00f3mina?\" width=\"1354\" height=\"537\" srcset=\"https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX255-300x119.webp 300w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX255-1024x405.webp 1024w, https:\/\/runahr.com\/wp-content\/uploads\/2026\/01\/CMX255-768x304.webp 768w\" sizes=\"(max-width: 1354px) 100vw, 1354px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue en 2014 cuando el Servicio de Administraci\u00f3n Tributaria (SAT) comand\u00f3 obligatoria la expedici\u00f3n de facturas electr\u00f3nicas para los contribuyentes f\u00edsicos y morales con actividad empresarial. Desde entonces, para desempe\u00f1ar sus actividades dentro de las normas es necesario que los contribuyentes cuenten con este servicio. Para lo cual es necesario un Proveedor Autorizado de Certificaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1022576,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_wp_applaud_exclude":false,"footnotes":""},"categories":[170,190],"tags":[1297,369,362],"class_list":["post-701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nomina","category-recursos","tag-articulo","tag-nomina-mx","tag-pac-mx"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfC\u00f3mo seleccionar un PAC adecuado? | Runa HR<\/title>\n<meta name=\"description\" content=\"Los contribuyentes deben contar con un servicio de facturaci\u00f3n electr\u00f3nica o Proveedor Autorizado de Certificaci\u00f3n (PAC).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo seleccionar un PAC adecuado? | MX | Runa HR\" \/>\n<meta property=\"og:description\" content=\"Los contribuyentes deben contar con un servicio de facturaci\u00f3n electr\u00f3nica o Proveedor Autorizado de Certificaci\u00f3n (PAC).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/\" \/>\n<meta property=\"og:site_name\" content=\"Runa HR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/runahr\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-09T06:21:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-21T20:26:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/runahr.com\/wp-content\/uploads\/2025\/04\/image-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Runa HR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfC\u00f3mo seleccionar un PAC adecuado? | Runa HR\" \/>\n<meta name=\"twitter:description\" content=\"Es necesario que los contribuyentes cuenten con servicio de facturaci\u00f3n electr\u00f3nica, por lo cual es importante contar con un Proveedor Autorizado de Certificaci\u00f3n (PAC).\" \/>\n<meta name=\"twitter:creator\" content=\"@runahr\" \/>\n<meta name=\"twitter:site\" content=\"@runahr\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Runa HR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo seleccionar un PAC adecuado? | Runa HR","description":"Los contribuyentes deben contar con un servicio de facturaci\u00f3n electr\u00f3nica o Proveedor Autorizado de Certificaci\u00f3n (PAC).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfC\u00f3mo seleccionar un PAC adecuado? | MX | Runa HR","og_description":"Los contribuyentes deben contar con un servicio de facturaci\u00f3n electr\u00f3nica o Proveedor Autorizado de Certificaci\u00f3n (PAC).","og_url":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/","og_site_name":"Runa HR","article_publisher":"https:\/\/www.facebook.com\/runahr\/","article_published_time":"2017-11-09T06:21:32+00:00","article_modified_time":"2026-02-21T20:26:14+00:00","og_image":[{"width":512,"height":286,"url":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/04\/image-2.png","type":"image\/png"}],"author":"Runa HR","twitter_card":"summary_large_image","twitter_title":"\u00bfC\u00f3mo seleccionar un PAC adecuado? | Runa HR","twitter_description":"Es necesario que los contribuyentes cuenten con servicio de facturaci\u00f3n electr\u00f3nica, por lo cual es importante contar con un Proveedor Autorizado de Certificaci\u00f3n (PAC).","twitter_creator":"@runahr","twitter_site":"@runahr","twitter_misc":{"Escrito por":"Runa HR","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/#article","isPartOf":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/"},"author":{"name":"Runa HR","@id":"https:\/\/runahr.com\/mx\/#\/schema\/person\/48bc8e24ad03cc8f426d7d8c9867bc83"},"headline":"\u00bfC\u00f3mo seleccionar un PAC adecuado?","datePublished":"2017-11-09T06:21:32+00:00","dateModified":"2026-02-21T20:26:14+00:00","mainEntityOfPage":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/"},"wordCount":417,"publisher":{"@id":"https:\/\/runahr.com\/mx\/#organization"},"image":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/#primaryimage"},"thumbnailUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/\u00bfComo-seleccionar-un-PAC-adecuado-.svg","keywords":["Art\u00edculo","N\u00f3mina","PAC"],"articleSection":["N\u00f3mina","Recursos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/","url":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/","name":"\u00bfC\u00f3mo seleccionar un PAC adecuado? | Runa HR","isPartOf":{"@id":"https:\/\/runahr.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/#primaryimage"},"image":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/#primaryimage"},"thumbnailUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/\u00bfComo-seleccionar-un-PAC-adecuado-.svg","datePublished":"2017-11-09T06:21:32+00:00","dateModified":"2026-02-21T20:26:14+00:00","description":"Los contribuyentes deben contar con un servicio de facturaci\u00f3n electr\u00f3nica o Proveedor Autorizado de Certificaci\u00f3n (PAC).","breadcrumb":{"@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/#primaryimage","url":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/\u00bfComo-seleccionar-un-PAC-adecuado-.svg","contentUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2025\/09\/\u00bfComo-seleccionar-un-PAC-adecuado-.svg","width":1090,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/runahr.com\/mx\/recursos\/nomina\/como-seleccionar-el-pac-adecuado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/runahr.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Recursos","item":"https:\/\/runahr.com\/mx\/category\/recursos\/"},{"@type":"ListItem","position":3,"name":"N\u00f3mina","item":"https:\/\/runahr.com\/mx\/category\/recursos\/nomina\/"},{"@type":"ListItem","position":4,"name":"\u00bfC\u00f3mo seleccionar un PAC adecuado?"}]},{"@type":"WebSite","@id":"https:\/\/runahr.com\/mx\/#website","url":"https:\/\/runahr.com\/mx\/","name":"Runa HR","description":"Software de N\u00f3mina y Gesti\u00f3n de RRHH","publisher":{"@id":"https:\/\/runahr.com\/mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/runahr.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/runahr.com\/mx\/#organization","name":"Runa HR","url":"https:\/\/runahr.com\/mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/runahr.com\/mx\/#\/schema\/logo\/image\/","url":"https:\/\/runahr.com\/wp-content\/uploads\/2018\/05\/xDzHFcQY_400x400.jpg","contentUrl":"https:\/\/runahr.com\/wp-content\/uploads\/2018\/05\/xDzHFcQY_400x400.jpg","width":400,"height":400,"caption":"Runa HR"},"image":{"@id":"https:\/\/runahr.com\/mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/runahr\/","https:\/\/x.com\/runahr","https:\/\/www.instagram.com\/runahr\/","https:\/\/mx.linkedin.com\/company\/runahr","https:\/\/www.youtube.com\/channel\/UCAZ21FupFMLIb1c7PPaU6Ew"]},{"@type":"Person","@id":"https:\/\/runahr.com\/mx\/#\/schema\/person\/48bc8e24ad03cc8f426d7d8c9867bc83","name":"Runa HR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0f5e3da5817edb54f2baf42e521fcc5bf236eed18b9dca62e6fa95f35ad83b5a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f5e3da5817edb54f2baf42e521fcc5bf236eed18b9dca62e6fa95f35ad83b5a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f5e3da5817edb54f2baf42e521fcc5bf236eed18b9dca62e6fa95f35ad83b5a?s=96&d=mm&r=g","caption":"Runa HR"},"sameAs":["https:\/\/runahr.com"],"url":"https:\/\/runahr.com\/mx\/author\/runahr\/"}]}},"_links":{"self":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/posts\/701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/comments?post=701"}],"version-history":[{"count":0,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/posts\/701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/media\/1022576"}],"wp:attachment":[{"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/media?parent=701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/categories?post=701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/runahr.com\/mx\/wp-json\/wp\/v2\/tags?post=701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}